    {"id":22,"date":"2026-01-22T16:23:24","date_gmt":"2026-01-22T21:23:24","guid":{"rendered":"https:\/\/federacionfesoc.org\/?page_id=22"},"modified":"2026-03-04T06:23:42","modified_gmt":"2026-03-04T11:23:42","slug":"inicio","status":"publish","type":"page","link":"https:\/\/federacionfesoc.org\/","title":{"rendered":"Inicio"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"22\" class=\"elementor elementor-22\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-729cebc e-con-full e-flex e-con e-parent\" data-id=\"729cebc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d44f84a elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"d44f84a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-17e9758 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg elementor-ken-burns elementor-ken-burns--in\" role=\"img\"><\/div><div class=\"elementor-background-overlay\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Federaci\u00f3n de empresas, sociales, solidarias, agroindustriales, consejos comunitarios y religiosas de Colombia<\/div><div class=\"elementor-slide-description\">Creemos en la calidad de nuestro trabajo como mayor garant\u00eda y fuente de satisfacci\u00f3n hacia la labor realizada.<\/div><\/div><\/div><\/div><div class=\"elementor-repeater-item-62af2be swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg elementor-ken-burns elementor-ken-burns--in\" role=\"img\"><\/div><div class=\"elementor-background-overlay\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\"> Ecoaldeas Productivas Solidarias<\/div><\/div><\/div><\/div><div class=\"elementor-repeater-item-7e2f251 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg elementor-ken-burns elementor-ken-burns--in\" role=\"img\"><\/div><div class=\"elementor-background-overlay\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Lazos Productivos<\/div><\/div><\/div><\/div><div class=\"elementor-repeater-item-ec74fbf swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg elementor-ken-burns elementor-ken-burns--in\" role=\"img\"><\/div><div class=\"elementor-background-overlay\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Intercambio Cultural<\/div><\/div><\/div><\/div><div class=\"elementor-repeater-item-a572e63 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg elementor-ken-burns elementor-ken-burns--in\" role=\"img\"><\/div><div class=\"elementor-background-overlay\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Educaci\u00f3n, Cultura y Deporte Social<\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous slide\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next slide\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b458a4a e-grid e-con-boxed e-con e-parent\" data-id=\"b458a4a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-57a4cef e-con-full e-flex e-con e-child\" data-id=\"57a4cef\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4f154b2 elementor-widget elementor-widget-text-editor\" data-id=\"4f154b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Hemos sido designados para liderar y gestionar integralmente las <strong>AYUDAS HUMANITARIAS<\/strong>, brindando apoyo a fundaciones, asociaciones, organismos sociales y empresas privadas en el desarrollo de proyectos con impacto y enfoque social, garantizando beneficios para todas las organizaciones afiliadas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-752904a e-grid e-con-boxed e-con e-parent\" data-id=\"752904a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a8b6278 elementor-widget elementor-widget-image\" data-id=\"a8b6278\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"277\" height=\"300\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-02-20-at-09.16.18-277x300.jpeg\" class=\"attachment-medium size-medium wp-image-592\" alt=\"\" srcset=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-02-20-at-09.16.18-277x300.jpeg 277w, https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-02-20-at-09.16.18-944x1024.jpeg 944w, https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-02-20-at-09.16.18-768x833.jpeg 768w, https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-02-20-at-09.16.18-1416x1536.jpeg 1416w, https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-02-20-at-09.16.18.jpeg 1418w\" sizes=\"(max-width: 277px) 100vw, 277px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4177771 e-flex e-con-boxed e-con e-parent\" data-id=\"4177771\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c5250c2 elementor-widget elementor-widget-heading\" data-id=\"c5250c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Organizaciones afiliadas con marco de trabajo especial Con enfoque agro<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d85594e elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"d85594e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;6&quot;,&quot;slides_to_scroll&quot;:&quot;6&quot;,&quot;autoplay_speed&quot;:2000,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel de im\u00e1genes\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/logo44-300x200.png\" alt=\"logo44\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/logo43-300x200.png\" alt=\"logo43\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/logo41-300x200.png\" alt=\"logo41\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/logo42-300x200.png\" alt=\"logo42\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/logo40-300x200.png\" alt=\"logo40\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/logo33-300x200.png\" alt=\"logo33\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/logo31-300x200.png\" alt=\"logo31\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/logo32-300x200.png\" alt=\"logo32\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/logo34-300x200.png\" alt=\"logo34\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/logo29-300x200.png\" alt=\"logo29\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/logo30-300x200.png\" alt=\"logo30\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/logo26-300x200.png\" alt=\"logo26\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/logo27-300x200.png\" alt=\"logo27\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/logo28-300x200.png\" alt=\"logo28\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"15 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/logo25-300x200.png\" alt=\"logo25\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"16 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/logo23-300x200.png\" alt=\"logo23\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"17 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/logo24-300x200.png\" alt=\"logo24\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"18 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/logo22-300x200.png\" alt=\"logo22\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"19 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/logo9-300x200.png\" alt=\"logo9\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"20 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/logo20-300x200.png\" alt=\"logo20\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"21 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/logo11-300x200.png\" alt=\"logo11\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"22 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/logo12-300x200.png\" alt=\"logo12\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"23 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/logo16-300x200.png\" alt=\"logo16\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"24 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/logo19-300x200.png\" alt=\"logo19\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"25 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/logo21-300x200.png\" alt=\"logo21\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"26 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/logo13-300x200.png\" alt=\"logo13\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"27 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/logo14-300x200.png\" alt=\"logo14\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"28 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/logo15-300x200.png\" alt=\"logo15\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"29 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/logo17-300x200.png\" alt=\"logo17\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"30 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/logo18-300x200.png\" alt=\"logo18\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"31 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/logo10-300x200.png\" alt=\"logo10\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"32 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/logo8-300x200.png\" alt=\"logo8\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"33 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/logo7-300x200.png\" alt=\"logo7\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"34 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/logo6-300x200.png\" alt=\"logo6\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"35 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/logo5-300x200.png\" alt=\"logo5\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"36 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/logo4-300x200.png\" alt=\"logo4\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"37 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/logo3-300x200.png\" alt=\"logo3\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"38 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/logo2-300x200.png\" alt=\"logo2\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"39 of 39\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/logo1-300x200.png\" alt=\"logo1\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5e35f21 e-grid e-con-boxed elementor-invisible e-con e-parent\" data-id=\"5e35f21\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInDown&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6b3c513 elementor-widget elementor-widget-text-editor\" data-id=\"6b3c513\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Creemos en la calidad de nuestro trabajo como mayor garant\u00eda y fuente de satisfacci\u00f3n hacia la labor realizada.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50a3a14 elementor-widget elementor-widget-text-editor\" data-id=\"50a3a14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Una vivienda digna es uno de los ejes fundamentales del mejoramiento de las condiciones de vida de nuestros afiliados.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39fc4f5 elementor-widget elementor-widget-text-editor\" data-id=\"39fc4f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Ayudamos en la realizaci\u00f3n de asesor\u00edas y gesti\u00f3n de proyectos entres entidades publicas y organizaciones.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-52ed1c8 e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"52ed1c8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;swing&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-625fb72 elementor-widget elementor-widget-heading\" data-id=\"625fb72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00daltimas noticias<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a674f76 elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-widget elementor-widget-posts\" data-id=\"a674f76\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;classic_columns&quot;:&quot;3&quot;,&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-772 post type-post status-publish format-standard has-post-thumbnail hentry category-sin-categoria\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/federacionfesoc.org\/index.php\/2026\/06\/18\/capacitacion-financiera-restrepo-valle-del-cauca\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-09-at-12.49.45-PM-300x225.jpeg\" class=\"attachment-medium size-medium wp-image-752\" alt=\"\" srcset=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-09-at-12.49.45-PM-300x225.jpeg 300w, https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-09-at-12.49.45-PM-1024x768.jpeg 1024w, https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-09-at-12.49.45-PM-768x576.jpeg 768w, https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-09-at-12.49.45-PM-1536x1152.jpeg 1536w, https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-09-at-12.49.45-PM.jpeg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/federacionfesoc.org\/index.php\/2026\/06\/18\/capacitacion-financiera-restrepo-valle-del-cauca\/\" >\n\t\t\t\tCapacitaci\u00f3n financiera Restrepo valle del cauca\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t18 junio, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/federacionfesoc.org\/index.php\/2026\/06\/18\/capacitacion-financiera-restrepo-valle-del-cauca\/\" aria-label=\"Read more about Capacitaci\u00f3n financiera Restrepo valle del cauca\" tabindex=\"-1\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-767 post type-post status-publish format-standard has-post-thumbnail hentry category-sin-categoria\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/federacionfesoc.org\/index.php\/2026\/06\/17\/reunion-de-junta-diretiva\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-09-at-1.09.09-PM-300x300.jpeg\" class=\"attachment-medium size-medium wp-image-758\" alt=\"\" srcset=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-09-at-1.09.09-PM-300x300.jpeg 300w, https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-09-at-1.09.09-PM-1024x1024.jpeg 1024w, https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-09-at-1.09.09-PM-150x150.jpeg 150w, https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-09-at-1.09.09-PM-768x768.jpeg 768w, https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-09-at-1.09.09-PM.jpeg 1080w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/federacionfesoc.org\/index.php\/2026\/06\/17\/reunion-de-junta-diretiva\/\" >\n\t\t\t\tFeliz Cumplea\u00f1os Doctor Heribert\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t17 junio, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/federacionfesoc.org\/index.php\/2026\/06\/17\/reunion-de-junta-diretiva\/\" aria-label=\"Read more about Feliz Cumplea\u00f1os Doctor Heribert\" tabindex=\"-1\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-749 post type-post status-publish format-standard has-post-thumbnail hentry category-sin-categoria\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/federacionfesoc.org\/index.php\/2026\/06\/09\/capacitacion-sevilla-com-los-consejos\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"205\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-09-at-1.02.06-PM-300x205.jpeg\" class=\"attachment-medium size-medium wp-image-755\" alt=\"\" srcset=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-09-at-1.02.06-PM-300x205.jpeg 300w, https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-09-at-1.02.06-PM-1024x699.jpeg 1024w, https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-09-at-1.02.06-PM-768x524.jpeg 768w, https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-09-at-1.02.06-PM.jpeg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/federacionfesoc.org\/index.php\/2026\/06\/09\/capacitacion-sevilla-com-los-consejos\/\" >\n\t\t\t\tHaciendo presencia en el D\u00eda de la afrocolombianidad con nuestros consejos comunitarios somos Colombia y mi nueva oportunidad desde el municipio de Restrepo valle del cauca\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t9 junio, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/federacionfesoc.org\/index.php\/2026\/06\/09\/capacitacion-sevilla-com-los-consejos\/\" aria-label=\"Read more about Haciendo presencia en el D\u00eda de la afrocolombianidad con nuestros consejos comunitarios somos Colombia y mi nueva oportunidad desde el municipio de Restrepo valle del cauca\" tabindex=\"-1\" >\n\t\t\tLeer m\u00e1s \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3c9319 elementor-invisible elementor-widget elementor-widget-button\" data-id=\"e3c9319\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/federacionfesoc.org\/index.php\/noticias\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ver todas las noticias <\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-579b170 e-flex e-con-boxed e-con e-parent\" data-id=\"579b170\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-515105d e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"515105d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;slideInLeft&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6ab2aff elementor-widget elementor-widget-image\" data-id=\"6ab2aff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/Insignia-1024x768.jpg\" class=\"attachment-large size-large wp-image-234\" alt=\"\" srcset=\"https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/Insignia-1024x768.jpg 1024w, https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/Insignia-300x225.jpg 300w, https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/Insignia-768x576.jpg 768w, https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/Insignia-1536x1152.jpg 1536w, https:\/\/federacionfesoc.org\/wp-content\/uploads\/2026\/01\/Insignia-2048x1536.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ba65ee5 e-con-full e-flex e-con e-child\" data-id=\"ba65ee5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-019da8c elementor-widget elementor-widget-text-editor\" data-id=\"019da8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h5>Recibe varios beneficios afiliandote a la federaci\u00f3n, para mas informaci\u00f3n contactanos, envianos un mensaje a <strong>administracion@federacionfesoc.org<\/strong> o inscribete.<br \/><br \/><\/h5><h5>Para pertenecer a <strong>FESOC<\/strong> se debe realizar un pago unico por afiliaci\u00f3n a partir de 3.5 a 10 Salarios Minimos Mensual Legal Vigente y un <strong>aporte mensua<\/strong>l a partir de <strong>$150.000 a $300.000<\/strong> como aporte administrativo, estas tarifas se otorga segun calificacion financiera y experiencia.<\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16cf6c6 elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"16cf6c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;rotateInUpLeft&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/federacionfesoc.org\/inscription\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Inscribirse<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Federaci\u00f3n de empresas, sociales, solidarias, agroindustriales, consejos comunitarios y religiosas de ColombiaCreemos en la calidad de nuestro trabajo como mayor garant\u00eda y fuente de satisfacci\u00f3n hacia la labor realizada. Ecoaldeas Productivas SolidariasLazos ProductivosIntercambio CulturalEducaci\u00f3n, Cultura y Deporte Social Hemos sido designados para liderar y gestionar integralmente las AYUDAS HUMANITARIAS, brindando apoyo a fundaciones, asociaciones, organismos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-22","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/federacionfesoc.org\/index.php\/wp-json\/wp\/v2\/pages\/22","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/federacionfesoc.org\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/federacionfesoc.org\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/federacionfesoc.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/federacionfesoc.org\/index.php\/wp-json\/wp\/v2\/comments?post=22"}],"version-history":[{"count":121,"href":"https:\/\/federacionfesoc.org\/index.php\/wp-json\/wp\/v2\/pages\/22\/revisions"}],"predecessor-version":[{"id":675,"href":"https:\/\/federacionfesoc.org\/index.php\/wp-json\/wp\/v2\/pages\/22\/revisions\/675"}],"wp:attachment":[{"href":"https:\/\/federacionfesoc.org\/index.php\/wp-json\/wp\/v2\/media?parent=22"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}